{"id":2753,"date":"2021-10-14T16:03:49","date_gmt":"2021-10-14T14:03:49","guid":{"rendered":"https:\/\/www.relevi.it\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/"},"modified":"2022-03-29T10:06:46","modified_gmt":"2022-03-29T08:06:46","slug":"spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains","status":"publish","type":"post","link":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/","title":{"rendered":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>C\u2019est vrai. Nous avons pris de nouvelles habitudes. Nous avons am\u00e9lior\u00e9 le niveau d\u2019hygi\u00e8ne et nous sommes tous de plus en plus attentifs \u00e0 notre sant\u00e9 et \u00e0 notre protection ainsi qu\u2019\u00e0 celles des personnes qui nous sont ch\u00e8res.  <br>Mais que dire de l\u2019hygi\u00e8ne dans la salle de bains? Pour chaque chasse d\u2019eau tir\u00e9e, ce sont de nombreuses bact\u00e9ries qui se propagent dans l\u2019air, contaminant les surfaces \u00e0 proximit\u00e9, les objets de la salle de bains et nos v\u00eatements. <\/p>\n\n\n\n<p>RELEVI propose une innovation dans le secteur avec: <strong>SPLUFF STOP GERMS<\/strong>. Il s\u2019agit d\u2019un bloc antibact\u00e9rien pour les WC, qui, comme un dispositif automatique, assure \u00e0 chaque chasse d\u2019eau tir\u00e9e une protection constante contre les bact\u00e9ries. <\/p>\n\n\n\n<p>En plus d\u2019\u00e9liminer les bact\u00e9ries et d\u2019assurer une hygi\u00e8ne parfaite de vos WC, il exerce une action anticalcaire pour plus de 150 chasses d\u2019eau. Il est pr\u00e9sent\u00e9 dans une nouvelle cage avec fentes sp\u00e9ciales ouvertes uniquement vers l\u2019int\u00e9rieur et en contact direct avec la surface des WC. Ces blocs ont \u00e9t\u00e9 d\u00e9velopp\u00e9s et sp\u00e9cialement test\u00e9s pour \u00eatre efficaces \u00e0 chaque chasse d\u2019eau, afin d\u2019\u00e9liminer les bact\u00e9ries.  <\/p>\n\n\n\n<p><strong>SPLUFF STOP GERMS, hygi\u00e8ne permanente dans la salle de bains.<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.relevi.it\/fr\/produits\/marque-relevi\/\">Brand Relevi<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS-791x1024.jpeg\" alt=\"\" class=\"wp-image-2155\" srcset=\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS-791x1024.jpeg 791w, https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS-232x300.jpeg 232w, https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS-768x994.jpeg 768w, https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS-1187x1536.jpeg 1187w, https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/SPLUFF-STOP-GERMS.jpeg 1280w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une hygi\u00e8ne parfaite dans la salle de bains? RELEVI propose une innovation dans le secteur: un bloc antibact\u00e9rien qui, comme un dispositif automatique, assure une protection constante contre les bact\u00e9ries.  <\/p>\n","protected":false},"author":1,"featured_media":2154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-2753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hygiene-de-la-salle-de-bain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi\" \/>\n<meta property=\"og:description\" content=\"Une hygi\u00e8ne parfaite dans la salle de bains? RELEVI propose une innovation dans le secteur: un bloc antibact\u00e9rien qui, comme un dispositif automatique, assure une protection constante contre les bact\u00e9ries.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\" \/>\n<meta property=\"og:site_name\" content=\"Relevi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RELEVISPA\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T14:03:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-29T08:06:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"studiokina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"studiokina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\"},\"author\":{\"name\":\"studiokina\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/e388aba95bce69a170aa1ce9e83894c2\"},\"headline\":\"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS\",\"datePublished\":\"2021-10-14T14:03:49+00:00\",\"dateModified\":\"2022-03-29T08:06:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"http:\/\/www.relevi.it\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg\",\"articleSection\":[\"Hygi\u00e8ne de la salle de bain\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\",\"url\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\",\"name\":\"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi\",\"isPartOf\":{\"@id\":\"http:\/\/www.relevi.it\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg\",\"datePublished\":\"2021-10-14T14:03:49+00:00\",\"dateModified\":\"2022-03-29T08:06:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage\",\"url\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg\",\"contentUrl\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg\",\"width\":1440,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Relevi\",\"item\":\"http:\/\/www.relevi.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hygi\u00e8ne de la salle de bain\",\"item\":\"https:\/\/www.relevi.it\/fr\/category\/hygiene-de-la-salle-de-bain\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#website\",\"url\":\"http:\/\/www.relevi.it\/fr\/\",\"name\":\"Relevi\",\"description\":\"Prodotti per l\u2019igiene e la deodorazione della casa\",\"publisher\":{\"@id\":\"http:\/\/www.relevi.it\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.relevi.it\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#organization\",\"name\":\"Relevi SPA\",\"url\":\"http:\/\/www.relevi.it\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2021\/12\/relevi_logo.png\",\"contentUrl\":\"https:\/\/www.relevi.it\/wp-content\/uploads\/2021\/12\/relevi_logo.png\",\"width\":3126,\"height\":2036,\"caption\":\"Relevi SPA\"},\"image\":{\"@id\":\"http:\/\/www.relevi.it\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/RELEVISPA\",\"https:\/\/www.linkedin.com\/company\/relevi-spa\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/e388aba95bce69a170aa1ce9e83894c2\",\"name\":\"studiokina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.relevi.it\/wp-content\/litespeed\/avatar\/1f17ede57c1b8bac686adee76ae58957.jpg?ver=1784025670\",\"contentUrl\":\"https:\/\/www.relevi.it\/wp-content\/litespeed\/avatar\/1f17ede57c1b8bac686adee76ae58957.jpg?ver=1784025670\",\"caption\":\"studiokina\"},\"sameAs\":[\"http:\/\/www.relevi.it\"],\"url\":\"https:\/\/www.relevi.it\/fr\/author\/studiokina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/","og_locale":"fr_FR","og_type":"article","og_title":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi","og_description":"Une hygi\u00e8ne parfaite dans la salle de bains? RELEVI propose une innovation dans le secteur: un bloc antibact\u00e9rien qui, comme un dispositif automatique, assure une protection constante contre les bact\u00e9ries.","og_url":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/","og_site_name":"Relevi","article_publisher":"https:\/\/www.facebook.com\/RELEVISPA","article_published_time":"2021-10-14T14:03:49+00:00","article_modified_time":"2022-03-29T08:06:46+00:00","og_image":[{"width":1440,"height":1920,"url":"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg","type":"image\/jpeg"}],"author":"studiokina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"studiokina","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#article","isPartOf":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/"},"author":{"name":"studiokina","@id":"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/e388aba95bce69a170aa1ce9e83894c2"},"headline":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS","datePublished":"2021-10-14T14:03:49+00:00","dateModified":"2022-03-29T08:06:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/"},"wordCount":236,"publisher":{"@id":"http:\/\/www.relevi.it\/fr\/#organization"},"image":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage"},"thumbnailUrl":"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg","articleSection":["Hygi\u00e8ne de la salle de bain"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/","url":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/","name":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS - Relevi","isPartOf":{"@id":"http:\/\/www.relevi.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage"},"image":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage"},"thumbnailUrl":"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg","datePublished":"2021-10-14T14:03:49+00:00","dateModified":"2022-03-29T08:06:46+00:00","breadcrumb":{"@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#primaryimage","url":"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg","contentUrl":"https:\/\/www.relevi.it\/wp-content\/uploads\/2022\/02\/spluff-stop.jpeg","width":1440,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.relevi.it\/fr\/spluff-stop-germs-un-tournant-dans-lhygiene-de-la-salle-de-bains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Relevi","item":"http:\/\/www.relevi.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Hygi\u00e8ne de la salle de bain","item":"https:\/\/www.relevi.it\/fr\/category\/hygiene-de-la-salle-de-bain\/"},{"@type":"ListItem","position":3,"name":"SPLUFF STOP GERMS: UN TOURNANT DANS L\u2019HYGI\u00c8NE DE LA SALLE DE BAINS"}]},{"@type":"WebSite","@id":"http:\/\/www.relevi.it\/fr\/#website","url":"http:\/\/www.relevi.it\/fr\/","name":"Relevi","description":"Prodotti per l\u2019igiene e la deodorazione della casa","publisher":{"@id":"http:\/\/www.relevi.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.relevi.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/www.relevi.it\/fr\/#organization","name":"Relevi SPA","url":"http:\/\/www.relevi.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.relevi.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.relevi.it\/wp-content\/uploads\/2021\/12\/relevi_logo.png","contentUrl":"https:\/\/www.relevi.it\/wp-content\/uploads\/2021\/12\/relevi_logo.png","width":3126,"height":2036,"caption":"Relevi SPA"},"image":{"@id":"http:\/\/www.relevi.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RELEVISPA","https:\/\/www.linkedin.com\/company\/relevi-spa\/"]},{"@type":"Person","@id":"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/e388aba95bce69a170aa1ce9e83894c2","name":"studiokina","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.relevi.it\/fr\/#\/schema\/person\/image\/","url":"https:\/\/www.relevi.it\/wp-content\/litespeed\/avatar\/1f17ede57c1b8bac686adee76ae58957.jpg?ver=1784025670","contentUrl":"https:\/\/www.relevi.it\/wp-content\/litespeed\/avatar\/1f17ede57c1b8bac686adee76ae58957.jpg?ver=1784025670","caption":"studiokina"},"sameAs":["http:\/\/www.relevi.it"],"url":"https:\/\/www.relevi.it\/fr\/author\/studiokina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/posts\/2753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/comments?post=2753"}],"version-history":[{"count":5,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/posts\/2753\/revisions"}],"predecessor-version":[{"id":2952,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/posts\/2753\/revisions\/2952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/media\/2154"}],"wp:attachment":[{"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/media?parent=2753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/categories?post=2753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.relevi.it\/fr\/wp-json\/wp\/v2\/tags?post=2753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}